{"id":412,"count":2,"description":"","link":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/","name":"arvostelu","slug":"arvostelu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>arvostelu - Americana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"arvostelu - Americana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/\" \/>\n<meta property=\"og:site_name\" content=\"Americana\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suomenkuvalehti.fi\/americana\/wp-content\/uploads\/sites\/10\/2022\/04\/americana_maunula-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/\",\"url\":\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/\",\"name\":\"arvostelu - Americana\",\"isPartOf\":{\"@id\":\"https:\/\/suomenkuvalehti.fi\/americana\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/suomenkuvalehti.fi\/americana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"arvostelu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/suomenkuvalehti.fi\/americana\/#website\",\"url\":\"https:\/\/suomenkuvalehti.fi\/americana\/\",\"name\":\"Americana\",\"description\":\"Professori Marko Maunula seuraa USA:n politiikkaa ja populaarikulttuuria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/suomenkuvalehti.fi\/haku\/?q={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"arvostelu - Americana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/","og_locale":"fi_FI","og_type":"article","og_title":"arvostelu - Americana","og_url":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/","og_site_name":"Americana","og_image":[{"width":2560,"height":1706,"url":"https:\/\/suomenkuvalehti.fi\/americana\/wp-content\/uploads\/sites\/10\/2022\/04\/americana_maunula-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/","url":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/","name":"arvostelu - Americana","isPartOf":{"@id":"https:\/\/suomenkuvalehti.fi\/americana\/#website"},"breadcrumb":{"@id":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/suomenkuvalehti.fi\/americana\/avainsana\/arvostelu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suomenkuvalehti.fi\/americana\/"},{"@type":"ListItem","position":2,"name":"arvostelu"}]},{"@type":"WebSite","@id":"https:\/\/suomenkuvalehti.fi\/americana\/#website","url":"https:\/\/suomenkuvalehti.fi\/americana\/","name":"Americana","description":"Professori Marko Maunula seuraa USA:n politiikkaa ja populaarikulttuuria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suomenkuvalehti.fi\/haku\/?q={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"_links":{"self":[{"href":"https:\/\/suomenkuvalehti.fi\/americana\/wp-json\/wp\/v2\/tags\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suomenkuvalehti.fi\/americana\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/suomenkuvalehti.fi\/americana\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/suomenkuvalehti.fi\/americana\/wp-json\/wp\/v2\/posts?tags=412"},{"href":"https:\/\/suomenkuvalehti.fi\/americana\/wp-json\/wp\/v2\/pages?tags=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}